{"id":1545,"date":"2026-01-20T10:35:37","date_gmt":"2026-01-20T09:35:37","guid":{"rendered":"https:\/\/essc-online.de\/v1\/?p=1545"},"modified":"2026-01-20T11:16:46","modified_gmt":"2026-01-20T10:16:46","slug":"erfolgreiche-master-in-ingelheim","status":"publish","type":"post","link":"https:\/\/essc-online.de\/v1\/erfolgreiche-master-in-ingelheim\/","title":{"rendered":"Erfolgreiche Master in Ingelheim"},"content":{"rendered":"\n<p>Beim 35. Internationale Masters, ausgerichtet vom 1. SSV Ingelheim, sind drei Masterschwimmer vom ESSC an den Start gegangen. Franz Fischer (AK 80) ging in seinen Hauptdisziplinen Brust und R\u00fccken an den Start und belegte hier zweimal den ersten Rang und dreimal den 2. Platz. Stefan John erzielte sein bestes Ergebnis \u00fcber 100m Lagen und wurde hier Erster. Des Weiteren wurde er Zweiter \u00fcber 50m Schmetterluing und 200m Brust sowei Dritter \u00fcber 100m Brust. Andreas Schramke \u00fcberraschte in der AK 50 mit einer tollen Zeit \u00fcber 100m Freistil i 1:08.86 min. und siegte \u00fcber diese Strecke.<\/p>\n\n\n\n<div data-wp-interactive=\"core\/file\" class=\"wp-block-file\"><object data-wp-bind--hidden=\"!state.hasPdfPreview\" hidden class=\"wp-block-file__embed\" data=\"https:\/\/essc-online.de\/v1\/wp-content\/uploads\/2026\/01\/protokoll.pdf\" type=\"application\/pdf\" style=\"width:100%;height:600px\" aria-label=\"Einbettung von protokoll.\"><\/object><a id=\"wp-block-file--media-bdc5d77c-c995-4a3b-8993-39d117c8a600\" href=\"https:\/\/essc-online.de\/v1\/wp-content\/uploads\/2026\/01\/protokoll.pdf\">protokoll<\/a><a href=\"https:\/\/essc-online.de\/v1\/wp-content\/uploads\/2026\/01\/protokoll.pdf\" class=\"wp-block-file__button wp-element-button\" download aria-describedby=\"wp-block-file--media-bdc5d77c-c995-4a3b-8993-39d117c8a600\">Herunterladen<\/a><\/div>\n","protected":false},"excerpt":{"rendered":"<p>Beim 35. Internationale Masters, ausgerichtet vom 1. SSV Ingelheim, sind drei Masterschwimmer vom ESSC an den Start gegangen. Franz Fischer (AK 80) ging in seinen Hauptdisziplinen Brust und R\u00fccken an den Start und belegte hier zweimal den ersten Rang und &hellip;<\/p>\n<p class=\"read-more\"> <a class=\"more-link\" href=\"https:\/\/essc-online.de\/v1\/erfolgreiche-master-in-ingelheim\/\"> <span class=\"screen-reader-text\">Erfolgreiche Master in Ingelheim<\/span> Weiterlesen &raquo;<\/a><\/p>\n","protected":false},"author":7,"featured_media":1546,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[3,32,31],"tags":[],"class_list":["post-1545","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-aktuelles","category-schwimmsport","category-wettkampfschwimmen-2026"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Erfolgreiche Master in Ingelheim - Erster Sodener Schwimm-Club 1927 e.V.<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/essc-online.de\/v1\/erfolgreiche-master-in-ingelheim\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Erfolgreiche Master in Ingelheim - Erster Sodener Schwimm-Club 1927 e.V.\" \/>\n<meta property=\"og:description\" content=\"Beim 35. Internationale Masters, ausgerichtet vom 1. SSV Ingelheim, sind drei Masterschwimmer vom ESSC an den Start gegangen. Franz Fischer (AK 80) ging in seinen Hauptdisziplinen Brust und R\u00fccken an den Start und belegte hier zweimal den ersten Rang und &hellip; Erfolgreiche Master in Ingelheim Weiterlesen &raquo;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/essc-online.de\/v1\/erfolgreiche-master-in-ingelheim\/\" \/>\n<meta property=\"og:site_name\" content=\"Erster Sodener Schwimm-Club 1927 e.V.\" \/>\n<meta property=\"article:published_time\" content=\"2026-01-20T09:35:37+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-01-20T10:16:46+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/essc-online.de\/v1\/wp-content\/uploads\/2026\/01\/PHOTO-2026-01-19-17-12-25.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2048\" \/>\n\t<meta property=\"og:image:height\" content=\"1630\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Frank Bender\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"Frank Bender\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"1\u00a0Minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/essc-online.de\\\/v1\\\/erfolgreiche-master-in-ingelheim\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/essc-online.de\\\/v1\\\/erfolgreiche-master-in-ingelheim\\\/\"},\"author\":{\"name\":\"Frank Bender\",\"@id\":\"https:\\\/\\\/essc-online.de\\\/v1\\\/#\\\/schema\\\/person\\\/31e43f8b9643670c68448a910ae1dcc4\"},\"headline\":\"Erfolgreiche Master in Ingelheim\",\"datePublished\":\"2026-01-20T09:35:37+00:00\",\"dateModified\":\"2026-01-20T10:16:46+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/essc-online.de\\\/v1\\\/erfolgreiche-master-in-ingelheim\\\/\"},\"wordCount\":96,\"publisher\":{\"@id\":\"https:\\\/\\\/essc-online.de\\\/v1\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/essc-online.de\\\/v1\\\/erfolgreiche-master-in-ingelheim\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/essc-online.de\\\/v1\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/PHOTO-2026-01-19-17-12-25.jpg?fit=2048%2C1630&ssl=1\",\"articleSection\":[\"Aktuelles\",\"Schwimmsport\",\"Wettkampfschwimmen 2026\"],\"inLanguage\":\"de\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/essc-online.de\\\/v1\\\/erfolgreiche-master-in-ingelheim\\\/\",\"url\":\"https:\\\/\\\/essc-online.de\\\/v1\\\/erfolgreiche-master-in-ingelheim\\\/\",\"name\":\"Erfolgreiche Master in Ingelheim - Erster Sodener Schwimm-Club 1927 e.V.\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/essc-online.de\\\/v1\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/essc-online.de\\\/v1\\\/erfolgreiche-master-in-ingelheim\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/essc-online.de\\\/v1\\\/erfolgreiche-master-in-ingelheim\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/essc-online.de\\\/v1\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/PHOTO-2026-01-19-17-12-25.jpg?fit=2048%2C1630&ssl=1\",\"datePublished\":\"2026-01-20T09:35:37+00:00\",\"dateModified\":\"2026-01-20T10:16:46+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/essc-online.de\\\/v1\\\/erfolgreiche-master-in-ingelheim\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/essc-online.de\\\/v1\\\/erfolgreiche-master-in-ingelheim\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/essc-online.de\\\/v1\\\/erfolgreiche-master-in-ingelheim\\\/#primaryimage\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/essc-online.de\\\/v1\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/PHOTO-2026-01-19-17-12-25.jpg?fit=2048%2C1630&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/essc-online.de\\\/v1\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/PHOTO-2026-01-19-17-12-25.jpg?fit=2048%2C1630&ssl=1\",\"width\":2048,\"height\":1630},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/essc-online.de\\\/v1\\\/erfolgreiche-master-in-ingelheim\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/essc-online.de\\\/v1\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Erfolgreiche Master in Ingelheim\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/essc-online.de\\\/v1\\\/#website\",\"url\":\"https:\\\/\\\/essc-online.de\\\/v1\\\/\",\"name\":\"Erster Sodener Schwimm-Club 1927 e.V.\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/essc-online.de\\\/v1\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/essc-online.de\\\/v1\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/essc-online.de\\\/v1\\\/#organization\",\"name\":\"Erster Sodener Schwimm-Club 1927 e.V.\",\"url\":\"https:\\\/\\\/essc-online.de\\\/v1\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/essc-online.de\\\/v1\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/essc-online.de\\\/v1\\\/wp-content\\\/uploads\\\/2025\\\/12\\\/Logo_ESSC.png?fit=640%2C193&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/essc-online.de\\\/v1\\\/wp-content\\\/uploads\\\/2025\\\/12\\\/Logo_ESSC.png?fit=640%2C193&ssl=1\",\"width\":640,\"height\":193,\"caption\":\"Erster Sodener Schwimm-Club 1927 e.V.\"},\"image\":{\"@id\":\"https:\\\/\\\/essc-online.de\\\/v1\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/essc-online.de\\\/v1\\\/#\\\/schema\\\/person\\\/31e43f8b9643670c68448a910ae1dcc4\",\"name\":\"Frank Bender\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/64c823cc3cf6656e3d4344f8cd7255fd7e47af8f1c60cf5ecae694d9dab25099?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/64c823cc3cf6656e3d4344f8cd7255fd7e47af8f1c60cf5ecae694d9dab25099?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/64c823cc3cf6656e3d4344f8cd7255fd7e47af8f1c60cf5ecae694d9dab25099?s=96&d=mm&r=g\",\"caption\":\"Frank Bender\"},\"url\":\"https:\\\/\\\/essc-online.de\\\/v1\\\/author\\\/fb\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Erfolgreiche Master in Ingelheim - Erster Sodener Schwimm-Club 1927 e.V.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/essc-online.de\/v1\/erfolgreiche-master-in-ingelheim\/","og_locale":"de_DE","og_type":"article","og_title":"Erfolgreiche Master in Ingelheim - Erster Sodener Schwimm-Club 1927 e.V.","og_description":"Beim 35. Internationale Masters, ausgerichtet vom 1. SSV Ingelheim, sind drei Masterschwimmer vom ESSC an den Start gegangen. Franz Fischer (AK 80) ging in seinen Hauptdisziplinen Brust und R\u00fccken an den Start und belegte hier zweimal den ersten Rang und &hellip; Erfolgreiche Master in Ingelheim Weiterlesen &raquo;","og_url":"https:\/\/essc-online.de\/v1\/erfolgreiche-master-in-ingelheim\/","og_site_name":"Erster Sodener Schwimm-Club 1927 e.V.","article_published_time":"2026-01-20T09:35:37+00:00","article_modified_time":"2026-01-20T10:16:46+00:00","og_image":[{"width":2048,"height":1630,"url":"https:\/\/essc-online.de\/v1\/wp-content\/uploads\/2026\/01\/PHOTO-2026-01-19-17-12-25.jpg","type":"image\/jpeg"}],"author":"Frank Bender","twitter_card":"summary_large_image","twitter_misc":{"Verfasst von":"Frank Bender","Gesch\u00e4tzte Lesezeit":"1\u00a0Minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/essc-online.de\/v1\/erfolgreiche-master-in-ingelheim\/#article","isPartOf":{"@id":"https:\/\/essc-online.de\/v1\/erfolgreiche-master-in-ingelheim\/"},"author":{"name":"Frank Bender","@id":"https:\/\/essc-online.de\/v1\/#\/schema\/person\/31e43f8b9643670c68448a910ae1dcc4"},"headline":"Erfolgreiche Master in Ingelheim","datePublished":"2026-01-20T09:35:37+00:00","dateModified":"2026-01-20T10:16:46+00:00","mainEntityOfPage":{"@id":"https:\/\/essc-online.de\/v1\/erfolgreiche-master-in-ingelheim\/"},"wordCount":96,"publisher":{"@id":"https:\/\/essc-online.de\/v1\/#organization"},"image":{"@id":"https:\/\/essc-online.de\/v1\/erfolgreiche-master-in-ingelheim\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/essc-online.de\/v1\/wp-content\/uploads\/2026\/01\/PHOTO-2026-01-19-17-12-25.jpg?fit=2048%2C1630&ssl=1","articleSection":["Aktuelles","Schwimmsport","Wettkampfschwimmen 2026"],"inLanguage":"de"},{"@type":"WebPage","@id":"https:\/\/essc-online.de\/v1\/erfolgreiche-master-in-ingelheim\/","url":"https:\/\/essc-online.de\/v1\/erfolgreiche-master-in-ingelheim\/","name":"Erfolgreiche Master in Ingelheim - Erster Sodener Schwimm-Club 1927 e.V.","isPartOf":{"@id":"https:\/\/essc-online.de\/v1\/#website"},"primaryImageOfPage":{"@id":"https:\/\/essc-online.de\/v1\/erfolgreiche-master-in-ingelheim\/#primaryimage"},"image":{"@id":"https:\/\/essc-online.de\/v1\/erfolgreiche-master-in-ingelheim\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/essc-online.de\/v1\/wp-content\/uploads\/2026\/01\/PHOTO-2026-01-19-17-12-25.jpg?fit=2048%2C1630&ssl=1","datePublished":"2026-01-20T09:35:37+00:00","dateModified":"2026-01-20T10:16:46+00:00","breadcrumb":{"@id":"https:\/\/essc-online.de\/v1\/erfolgreiche-master-in-ingelheim\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/essc-online.de\/v1\/erfolgreiche-master-in-ingelheim\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/essc-online.de\/v1\/erfolgreiche-master-in-ingelheim\/#primaryimage","url":"https:\/\/i0.wp.com\/essc-online.de\/v1\/wp-content\/uploads\/2026\/01\/PHOTO-2026-01-19-17-12-25.jpg?fit=2048%2C1630&ssl=1","contentUrl":"https:\/\/i0.wp.com\/essc-online.de\/v1\/wp-content\/uploads\/2026\/01\/PHOTO-2026-01-19-17-12-25.jpg?fit=2048%2C1630&ssl=1","width":2048,"height":1630},{"@type":"BreadcrumbList","@id":"https:\/\/essc-online.de\/v1\/erfolgreiche-master-in-ingelheim\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/essc-online.de\/v1\/"},{"@type":"ListItem","position":2,"name":"Erfolgreiche Master in Ingelheim"}]},{"@type":"WebSite","@id":"https:\/\/essc-online.de\/v1\/#website","url":"https:\/\/essc-online.de\/v1\/","name":"Erster Sodener Schwimm-Club 1927 e.V.","description":"","publisher":{"@id":"https:\/\/essc-online.de\/v1\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/essc-online.de\/v1\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/essc-online.de\/v1\/#organization","name":"Erster Sodener Schwimm-Club 1927 e.V.","url":"https:\/\/essc-online.de\/v1\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/essc-online.de\/v1\/#\/schema\/logo\/image\/","url":"https:\/\/i0.wp.com\/essc-online.de\/v1\/wp-content\/uploads\/2025\/12\/Logo_ESSC.png?fit=640%2C193&ssl=1","contentUrl":"https:\/\/i0.wp.com\/essc-online.de\/v1\/wp-content\/uploads\/2025\/12\/Logo_ESSC.png?fit=640%2C193&ssl=1","width":640,"height":193,"caption":"Erster Sodener Schwimm-Club 1927 e.V."},"image":{"@id":"https:\/\/essc-online.de\/v1\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/essc-online.de\/v1\/#\/schema\/person\/31e43f8b9643670c68448a910ae1dcc4","name":"Frank Bender","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/secure.gravatar.com\/avatar\/64c823cc3cf6656e3d4344f8cd7255fd7e47af8f1c60cf5ecae694d9dab25099?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/64c823cc3cf6656e3d4344f8cd7255fd7e47af8f1c60cf5ecae694d9dab25099?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/64c823cc3cf6656e3d4344f8cd7255fd7e47af8f1c60cf5ecae694d9dab25099?s=96&d=mm&r=g","caption":"Frank Bender"},"url":"https:\/\/essc-online.de\/v1\/author\/fb\/"}]}},"jetpack_featured_media_url":"https:\/\/i0.wp.com\/essc-online.de\/v1\/wp-content\/uploads\/2026\/01\/PHOTO-2026-01-19-17-12-25.jpg?fit=2048%2C1630&ssl=1","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/essc-online.de\/v1\/wp-json\/wp\/v2\/posts\/1545","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/essc-online.de\/v1\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/essc-online.de\/v1\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/essc-online.de\/v1\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/essc-online.de\/v1\/wp-json\/wp\/v2\/comments?post=1545"}],"version-history":[{"count":2,"href":"https:\/\/essc-online.de\/v1\/wp-json\/wp\/v2\/posts\/1545\/revisions"}],"predecessor-version":[{"id":1549,"href":"https:\/\/essc-online.de\/v1\/wp-json\/wp\/v2\/posts\/1545\/revisions\/1549"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/essc-online.de\/v1\/wp-json\/wp\/v2\/media\/1546"}],"wp:attachment":[{"href":"https:\/\/essc-online.de\/v1\/wp-json\/wp\/v2\/media?parent=1545"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/essc-online.de\/v1\/wp-json\/wp\/v2\/categories?post=1545"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/essc-online.de\/v1\/wp-json\/wp\/v2\/tags?post=1545"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}